{"id":1903,"date":"2012-10-07T13:37:12","date_gmt":"2012-10-07T12:37:12","guid":{"rendered":"http:\/\/linesfiction.de\/lfd\/?p=1903"},"modified":"2025-05-10T23:20:24","modified_gmt":"2025-05-10T22:20:24","slug":"norbert-trummer","status":"publish","type":"post","link":"https:\/\/linesfiction.de\/lfd\/norbert-trummer\/","title":{"rendered":"Norbert Trummer"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">Norbert Trummer: Mir gef\u00e4llt es, Zeichnung, Malerei und Film zu kombinieren, und mein Arbeitsproze\u00df stellt eine Beziehung zwischen den Medien her. Zuerst zeichne ich alles vor Ort genau so, wie es nachher im Buch erscheint, in der Gr\u00f6\u00dfe von 10,5 x 15 cm. Sp\u00e4ter w\u00e4hle ich aus diesen Zeichnungen bestimmte Motive f\u00fcr kleine Malereien aus. F\u00fcr \u201eKrumlovsommer\u201c entstanden aus jedem Motiv jeweils Serien von drei Bildern, mit Eitempera auf Papier, in der Gr\u00f6\u00dfe von 10 x 14 cm. Diese kleinen Malereien sind die Basis f\u00fcr die Animation, die Unterschiede im Malproze\u00df verursachen den schwappenden Eindruck in der Bewegung.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">In Ausstellungen zeige ich die Zeichnungen, die Malereien und den Film. Aber ich gebe jedem Medium am liebsten seinen eigenen Raum. Es ist f\u00fcr mich wichtig, da\u00df jedes Medium als Teil meines Konzeptes f\u00fcr sich stehen kann.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">&gt;&gt; <strong><a href=\"http:\/\/linesfiction.de\/lfd\/index.php\/lines-fiction-online\/m-z\/norbert-trummer\">Norbert Trummer<\/a><\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Norbert Trummer: Mir gef\u00e4llt es, Zeichnung, Malerei und Film zu kombinieren, und mein Arbeitsproze\u00df stellt eine Beziehung zwischen den Medien her. Zuerst zeichne ich alles vor Ort genau so, wie es nachher im Buch erscheint, in der Gr\u00f6\u00dfe von 10,5 &hellip;<\/p>\n<p class=\"read-more\"> <a class=\"more-link\" href=\"https:\/\/linesfiction.de\/lfd\/norbert-trummer\/\"> <span class=\"screen-reader-text\">Norbert Trummer<\/span> Weiterlesen &raquo;<\/a><\/p>\n","protected":false},"author":10,"featured_media":0,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[18,16,63],"tags":[68,20,69],"class_list":["post-1903","post","type-post","status-publish","format-standard","hentry","category-bild-fuer-bild-animation","category-geschichten-storytelling","category-installation","tag-farbstift","tag-gouache","tag-kuenstlerbuch"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Norbert Trummer - Lines Fiction \u2605 Zeichnung &amp; Animation \u2605<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/linesfiction.de\/lfd\/norbert-trummer\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Norbert Trummer - Lines Fiction \u2605 Zeichnung &amp; Animation \u2605\" \/>\n<meta property=\"og:description\" content=\"Norbert Trummer: Mir gef\u00e4llt es, Zeichnung, Malerei und Film zu kombinieren, und mein Arbeitsproze\u00df stellt eine Beziehung zwischen den Medien her. Zuerst zeichne ich alles vor Ort genau so, wie es nachher im Buch erscheint, in der Gr\u00f6\u00dfe von 10,5 &hellip; Norbert Trummer Weiterlesen &raquo;\" \/>\n<meta property=\"og:url\" content=\"https:\/\/linesfiction.de\/lfd\/norbert-trummer\/\" \/>\n<meta property=\"og:site_name\" content=\"Lines Fiction \u2605 Zeichnung &amp; Animation \u2605\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/linesfiction\/\" \/>\n<meta property=\"article:published_time\" content=\"2012-10-07T12:37:12+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-05-10T22:20:24+00:00\" \/>\n<meta name=\"author\" content=\"news\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@linesfiction\" \/>\n<meta name=\"twitter:site\" content=\"@linesfiction\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"news\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"1\u00a0Minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/linesfiction.de\\\/lfd\\\/norbert-trummer\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/linesfiction.de\\\/lfd\\\/norbert-trummer\\\/\"},\"author\":{\"name\":\"news\",\"@id\":\"https:\\\/\\\/linesfiction.de\\\/lfd\\\/#\\\/schema\\\/person\\\/810373e3981f38296100fdb1a09b571d\"},\"headline\":\"Norbert Trummer\",\"datePublished\":\"2012-10-07T12:37:12+00:00\",\"dateModified\":\"2025-05-10T22:20:24+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/linesfiction.de\\\/lfd\\\/norbert-trummer\\\/\"},\"wordCount\":147,\"publisher\":{\"@id\":\"https:\\\/\\\/linesfiction.de\\\/lfd\\\/#organization\"},\"keywords\":[\"Farbstift\",\"Gouache\",\"K\u00fcnstlerbuch\"],\"articleSection\":[\"Bild f\u00fcr Bild Animation\",\"Geschichten-Storytelling\",\"Installation\"],\"inLanguage\":\"de\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/linesfiction.de\\\/lfd\\\/norbert-trummer\\\/\",\"url\":\"https:\\\/\\\/linesfiction.de\\\/lfd\\\/norbert-trummer\\\/\",\"name\":\"Norbert Trummer - Lines Fiction \u2605 Zeichnung &amp; Animation \u2605\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/linesfiction.de\\\/lfd\\\/#website\"},\"datePublished\":\"2012-10-07T12:37:12+00:00\",\"dateModified\":\"2025-05-10T22:20:24+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/linesfiction.de\\\/lfd\\\/norbert-trummer\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/linesfiction.de\\\/lfd\\\/norbert-trummer\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/linesfiction.de\\\/lfd\\\/norbert-trummer\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/linesfiction.de\\\/lfd\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Norbert Trummer\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/linesfiction.de\\\/lfd\\\/#website\",\"url\":\"https:\\\/\\\/linesfiction.de\\\/lfd\\\/\",\"name\":\"Lines Fiction - Zeichnung & Animation - Drawing & Animation\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/linesfiction.de\\\/lfd\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/linesfiction.de\\\/lfd\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/linesfiction.de\\\/lfd\\\/#organization\",\"name\":\"Lines Fiction\",\"url\":\"https:\\\/\\\/linesfiction.de\\\/lfd\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/linesfiction.de\\\/lfd\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/linesfiction.de\\\/lfd\\\/wp-content\\\/uploads\\\/2022\\\/12\\\/linesfiction_logo_instagram.jpg\",\"contentUrl\":\"https:\\\/\\\/linesfiction.de\\\/lfd\\\/wp-content\\\/uploads\\\/2022\\\/12\\\/linesfiction_logo_instagram.jpg\",\"width\":1080,\"height\":1077,\"caption\":\"Lines Fiction\"},\"image\":{\"@id\":\"https:\\\/\\\/linesfiction.de\\\/lfd\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/linesfiction\\\/\",\"https:\\\/\\\/x.com\\\/linesfiction\",\"https:\\\/\\\/www.instagram.com\\\/linesfiction\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/linesfiction.de\\\/lfd\\\/#\\\/schema\\\/person\\\/810373e3981f38296100fdb1a09b571d\",\"name\":\"news\",\"url\":\"https:\\\/\\\/linesfiction.de\\\/lfd\\\/author\\\/news\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Norbert Trummer - Lines Fiction \u2605 Zeichnung &amp; Animation \u2605","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/linesfiction.de\/lfd\/norbert-trummer\/","og_locale":"de_DE","og_type":"article","og_title":"Norbert Trummer - Lines Fiction \u2605 Zeichnung &amp; Animation \u2605","og_description":"Norbert Trummer: Mir gef\u00e4llt es, Zeichnung, Malerei und Film zu kombinieren, und mein Arbeitsproze\u00df stellt eine Beziehung zwischen den Medien her. Zuerst zeichne ich alles vor Ort genau so, wie es nachher im Buch erscheint, in der Gr\u00f6\u00dfe von 10,5 &hellip; Norbert Trummer Weiterlesen &raquo;","og_url":"https:\/\/linesfiction.de\/lfd\/norbert-trummer\/","og_site_name":"Lines Fiction \u2605 Zeichnung &amp; Animation \u2605","article_publisher":"https:\/\/www.facebook.com\/linesfiction\/","article_published_time":"2012-10-07T12:37:12+00:00","article_modified_time":"2025-05-10T22:20:24+00:00","author":"news","twitter_card":"summary_large_image","twitter_creator":"@linesfiction","twitter_site":"@linesfiction","twitter_misc":{"Verfasst von":"news","Gesch\u00e4tzte Lesezeit":"1\u00a0Minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/linesfiction.de\/lfd\/norbert-trummer\/#article","isPartOf":{"@id":"https:\/\/linesfiction.de\/lfd\/norbert-trummer\/"},"author":{"name":"news","@id":"https:\/\/linesfiction.de\/lfd\/#\/schema\/person\/810373e3981f38296100fdb1a09b571d"},"headline":"Norbert Trummer","datePublished":"2012-10-07T12:37:12+00:00","dateModified":"2025-05-10T22:20:24+00:00","mainEntityOfPage":{"@id":"https:\/\/linesfiction.de\/lfd\/norbert-trummer\/"},"wordCount":147,"publisher":{"@id":"https:\/\/linesfiction.de\/lfd\/#organization"},"keywords":["Farbstift","Gouache","K\u00fcnstlerbuch"],"articleSection":["Bild f\u00fcr Bild Animation","Geschichten-Storytelling","Installation"],"inLanguage":"de"},{"@type":"WebPage","@id":"https:\/\/linesfiction.de\/lfd\/norbert-trummer\/","url":"https:\/\/linesfiction.de\/lfd\/norbert-trummer\/","name":"Norbert Trummer - Lines Fiction \u2605 Zeichnung &amp; Animation \u2605","isPartOf":{"@id":"https:\/\/linesfiction.de\/lfd\/#website"},"datePublished":"2012-10-07T12:37:12+00:00","dateModified":"2025-05-10T22:20:24+00:00","breadcrumb":{"@id":"https:\/\/linesfiction.de\/lfd\/norbert-trummer\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/linesfiction.de\/lfd\/norbert-trummer\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/linesfiction.de\/lfd\/norbert-trummer\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/linesfiction.de\/lfd\/"},{"@type":"ListItem","position":2,"name":"Norbert Trummer"}]},{"@type":"WebSite","@id":"https:\/\/linesfiction.de\/lfd\/#website","url":"https:\/\/linesfiction.de\/lfd\/","name":"Lines Fiction - Zeichnung & Animation - Drawing & Animation","description":"","publisher":{"@id":"https:\/\/linesfiction.de\/lfd\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/linesfiction.de\/lfd\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/linesfiction.de\/lfd\/#organization","name":"Lines Fiction","url":"https:\/\/linesfiction.de\/lfd\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/linesfiction.de\/lfd\/#\/schema\/logo\/image\/","url":"https:\/\/linesfiction.de\/lfd\/wp-content\/uploads\/2022\/12\/linesfiction_logo_instagram.jpg","contentUrl":"https:\/\/linesfiction.de\/lfd\/wp-content\/uploads\/2022\/12\/linesfiction_logo_instagram.jpg","width":1080,"height":1077,"caption":"Lines Fiction"},"image":{"@id":"https:\/\/linesfiction.de\/lfd\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/linesfiction\/","https:\/\/x.com\/linesfiction","https:\/\/www.instagram.com\/linesfiction\/"]},{"@type":"Person","@id":"https:\/\/linesfiction.de\/lfd\/#\/schema\/person\/810373e3981f38296100fdb1a09b571d","name":"news","url":"https:\/\/linesfiction.de\/lfd\/author\/news\/"}]}},"_links":{"self":[{"href":"https:\/\/linesfiction.de\/lfd\/wp-json\/wp\/v2\/posts\/1903","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/linesfiction.de\/lfd\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/linesfiction.de\/lfd\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/linesfiction.de\/lfd\/wp-json\/wp\/v2\/users\/10"}],"replies":[{"embeddable":true,"href":"https:\/\/linesfiction.de\/lfd\/wp-json\/wp\/v2\/comments?post=1903"}],"version-history":[{"count":3,"href":"https:\/\/linesfiction.de\/lfd\/wp-json\/wp\/v2\/posts\/1903\/revisions"}],"predecessor-version":[{"id":4028,"href":"https:\/\/linesfiction.de\/lfd\/wp-json\/wp\/v2\/posts\/1903\/revisions\/4028"}],"wp:attachment":[{"href":"https:\/\/linesfiction.de\/lfd\/wp-json\/wp\/v2\/media?parent=1903"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/linesfiction.de\/lfd\/wp-json\/wp\/v2\/categories?post=1903"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/linesfiction.de\/lfd\/wp-json\/wp\/v2\/tags?post=1903"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}