{"id":3981,"date":"2025-05-10T22:33:03","date_gmt":"2025-05-10T21:33:03","guid":{"rendered":"https:\/\/linesfiction.de\/lfd\/?p=3981"},"modified":"2026-03-29T14:13:11","modified_gmt":"2026-03-29T13:13:11","slug":"teresa-casanueva-und-maria-otterbein","status":"publish","type":"post","link":"https:\/\/linesfiction.de\/lfd\/teresa-casanueva-und-maria-otterbein\/","title":{"rendered":"Teresa Casanueva und Maria Otterbein"},"content":{"rendered":"\n<p>Maria Otterbein: Unsere Animationen bestehen im Wesentlichen aus vielen Ebenen, die miteinander kooperieren. In [IM]PULS Vol. 1 wird das Hauptmotiv mit einer Kombination aus Ereignissen umh\u00fcllt. Hierbei bilden sich Kontraste durch unterschiedliche Formensprachen, ihre Konsistenz, Eigenschaften und Strukturen. Elemente wachsen, ver\u00e4ndern sich oder verschwinden. Sie zeigen vielf\u00e4ltige Bewegungsabl\u00e4ufe, denen wir zur Erg\u00e4nzung differenzierte Kl\u00e4nge zugeordnet haben.<\/p>\n\n\n\n<p>Teresa Casanueva: Die ganze Arbeit basiert auf Ph\u00e4nomenen und Logik, die in der Natur vorhanden sind. Dieser unendliche Reichtum an M\u00f6glichkeiten ist f\u00fcr uns die Quelle und die Lehre, um ein eigenes Konstrukt und Bildsprache in der Arbeit zu entwickeln. Das Organische und das Maschinelle sind ein Verbund sowohl konzeptionell als auch funktional.<\/p>\n\n\n\n<p>&gt;&gt; <strong><a href=\"http:\/\/linesfiction.de\/lfd\/index.php\/lines-fiction-online\/a-l\/casanueva-otterbein\">Teresa Casanueva und Maria Otterbein<\/a><\/strong><\/p>\n\n\n\n<p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Maria Otterbein: Unsere Animationen bestehen im Wesentlichen aus vielen Ebenen, die miteinander kooperieren. In [IM]PULS Vol. 1 wird das Hauptmotiv mit einer Kombination aus Ereignissen umh\u00fcllt. Hierbei bilden sich Kontraste durch unterschiedliche Formensprachen, ihre Konsistenz, Eigenschaften und Strukturen. Elemente wachsen, &hellip;<\/p>\n<p class=\"read-more\"> <a class=\"more-link\" href=\"https:\/\/linesfiction.de\/lfd\/teresa-casanueva-und-maria-otterbein\/\"> <span class=\"screen-reader-text\">Teresa Casanueva und Maria Otterbein<\/span> Weiterlesen &raquo;<\/a><\/p>\n","protected":false},"author":9,"featured_media":0,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[94,19,17],"tags":[34],"class_list":["post-3981","post","type-post","status-publish","format-standard","hentry","category-abstract-art-in-motion","category-computergeneriert","category-experiment","tag-computeranimation"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Teresa Casanueva und Maria Otterbein - Lines Fiction \u2605 Zeichnung &amp; Animation \u2605<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/linesfiction.de\/lfd\/teresa-casanueva-und-maria-otterbein\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Teresa Casanueva und Maria Otterbein - Lines Fiction \u2605 Zeichnung &amp; Animation \u2605\" \/>\n<meta property=\"og:description\" content=\"Maria Otterbein: Unsere Animationen bestehen im Wesentlichen aus vielen Ebenen, die miteinander kooperieren. In [IM]PULS Vol. 1 wird das Hauptmotiv mit einer Kombination aus Ereignissen umh\u00fcllt. Hierbei bilden sich Kontraste durch unterschiedliche Formensprachen, ihre Konsistenz, Eigenschaften und Strukturen. Elemente wachsen, &hellip; Teresa Casanueva und Maria Otterbein Weiterlesen &raquo;\" \/>\n<meta property=\"og:url\" content=\"https:\/\/linesfiction.de\/lfd\/teresa-casanueva-und-maria-otterbein\/\" \/>\n<meta property=\"og:site_name\" content=\"Lines Fiction \u2605 Zeichnung &amp; Animation \u2605\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/linesfiction\/\" \/>\n<meta property=\"article:published_time\" content=\"2025-05-10T21:33:03+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-03-29T13:13:11+00:00\" \/>\n<meta name=\"author\" content=\"lines\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@linesfiction\" \/>\n<meta name=\"twitter:site\" content=\"@linesfiction\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"lines\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"1\u00a0Minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/linesfiction.de\\\/lfd\\\/teresa-casanueva-und-maria-otterbein\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/linesfiction.de\\\/lfd\\\/teresa-casanueva-und-maria-otterbein\\\/\"},\"author\":{\"name\":\"lines\",\"@id\":\"https:\\\/\\\/linesfiction.de\\\/lfd\\\/#\\\/schema\\\/person\\\/f8d3cb2f3f3d7c9d441be87acf0de8f4\"},\"headline\":\"Teresa Casanueva und Maria Otterbein\",\"datePublished\":\"2025-05-10T21:33:03+00:00\",\"dateModified\":\"2026-03-29T13:13:11+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/linesfiction.de\\\/lfd\\\/teresa-casanueva-und-maria-otterbein\\\/\"},\"wordCount\":130,\"publisher\":{\"@id\":\"https:\\\/\\\/linesfiction.de\\\/lfd\\\/#organization\"},\"keywords\":[\"Computeranimation\"],\"articleSection\":[\"Abstract Art in Motion\",\"Computergeneriert\",\"Experiment\"],\"inLanguage\":\"de\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/linesfiction.de\\\/lfd\\\/teresa-casanueva-und-maria-otterbein\\\/\",\"url\":\"https:\\\/\\\/linesfiction.de\\\/lfd\\\/teresa-casanueva-und-maria-otterbein\\\/\",\"name\":\"Teresa Casanueva und Maria Otterbein - Lines Fiction \u2605 Zeichnung &amp; Animation \u2605\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/linesfiction.de\\\/lfd\\\/#website\"},\"datePublished\":\"2025-05-10T21:33:03+00:00\",\"dateModified\":\"2026-03-29T13:13:11+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/linesfiction.de\\\/lfd\\\/teresa-casanueva-und-maria-otterbein\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/linesfiction.de\\\/lfd\\\/teresa-casanueva-und-maria-otterbein\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/linesfiction.de\\\/lfd\\\/teresa-casanueva-und-maria-otterbein\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/linesfiction.de\\\/lfd\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Teresa Casanueva und Maria Otterbein\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/linesfiction.de\\\/lfd\\\/#website\",\"url\":\"https:\\\/\\\/linesfiction.de\\\/lfd\\\/\",\"name\":\"Lines Fiction - Zeichnung & Animation - Drawing & Animation\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/linesfiction.de\\\/lfd\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/linesfiction.de\\\/lfd\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/linesfiction.de\\\/lfd\\\/#organization\",\"name\":\"Lines Fiction\",\"url\":\"https:\\\/\\\/linesfiction.de\\\/lfd\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/linesfiction.de\\\/lfd\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/linesfiction.de\\\/lfd\\\/wp-content\\\/uploads\\\/2022\\\/12\\\/linesfiction_logo_instagram.jpg\",\"contentUrl\":\"https:\\\/\\\/linesfiction.de\\\/lfd\\\/wp-content\\\/uploads\\\/2022\\\/12\\\/linesfiction_logo_instagram.jpg\",\"width\":1080,\"height\":1077,\"caption\":\"Lines Fiction\"},\"image\":{\"@id\":\"https:\\\/\\\/linesfiction.de\\\/lfd\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/linesfiction\\\/\",\"https:\\\/\\\/x.com\\\/linesfiction\",\"https:\\\/\\\/www.instagram.com\\\/linesfiction\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/linesfiction.de\\\/lfd\\\/#\\\/schema\\\/person\\\/f8d3cb2f3f3d7c9d441be87acf0de8f4\",\"name\":\"lines\",\"url\":\"https:\\\/\\\/linesfiction.de\\\/lfd\\\/author\\\/linesfiktion\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Teresa Casanueva und Maria Otterbein - Lines Fiction \u2605 Zeichnung &amp; Animation \u2605","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/linesfiction.de\/lfd\/teresa-casanueva-und-maria-otterbein\/","og_locale":"de_DE","og_type":"article","og_title":"Teresa Casanueva und Maria Otterbein - Lines Fiction \u2605 Zeichnung &amp; Animation \u2605","og_description":"Maria Otterbein: Unsere Animationen bestehen im Wesentlichen aus vielen Ebenen, die miteinander kooperieren. In [IM]PULS Vol. 1 wird das Hauptmotiv mit einer Kombination aus Ereignissen umh\u00fcllt. Hierbei bilden sich Kontraste durch unterschiedliche Formensprachen, ihre Konsistenz, Eigenschaften und Strukturen. Elemente wachsen, &hellip; Teresa Casanueva und Maria Otterbein Weiterlesen &raquo;","og_url":"https:\/\/linesfiction.de\/lfd\/teresa-casanueva-und-maria-otterbein\/","og_site_name":"Lines Fiction \u2605 Zeichnung &amp; Animation \u2605","article_publisher":"https:\/\/www.facebook.com\/linesfiction\/","article_published_time":"2025-05-10T21:33:03+00:00","article_modified_time":"2026-03-29T13:13:11+00:00","author":"lines","twitter_card":"summary_large_image","twitter_creator":"@linesfiction","twitter_site":"@linesfiction","twitter_misc":{"Verfasst von":"lines","Gesch\u00e4tzte Lesezeit":"1\u00a0Minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/linesfiction.de\/lfd\/teresa-casanueva-und-maria-otterbein\/#article","isPartOf":{"@id":"https:\/\/linesfiction.de\/lfd\/teresa-casanueva-und-maria-otterbein\/"},"author":{"name":"lines","@id":"https:\/\/linesfiction.de\/lfd\/#\/schema\/person\/f8d3cb2f3f3d7c9d441be87acf0de8f4"},"headline":"Teresa Casanueva und Maria Otterbein","datePublished":"2025-05-10T21:33:03+00:00","dateModified":"2026-03-29T13:13:11+00:00","mainEntityOfPage":{"@id":"https:\/\/linesfiction.de\/lfd\/teresa-casanueva-und-maria-otterbein\/"},"wordCount":130,"publisher":{"@id":"https:\/\/linesfiction.de\/lfd\/#organization"},"keywords":["Computeranimation"],"articleSection":["Abstract Art in Motion","Computergeneriert","Experiment"],"inLanguage":"de"},{"@type":"WebPage","@id":"https:\/\/linesfiction.de\/lfd\/teresa-casanueva-und-maria-otterbein\/","url":"https:\/\/linesfiction.de\/lfd\/teresa-casanueva-und-maria-otterbein\/","name":"Teresa Casanueva und Maria Otterbein - Lines Fiction \u2605 Zeichnung &amp; Animation \u2605","isPartOf":{"@id":"https:\/\/linesfiction.de\/lfd\/#website"},"datePublished":"2025-05-10T21:33:03+00:00","dateModified":"2026-03-29T13:13:11+00:00","breadcrumb":{"@id":"https:\/\/linesfiction.de\/lfd\/teresa-casanueva-und-maria-otterbein\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/linesfiction.de\/lfd\/teresa-casanueva-und-maria-otterbein\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/linesfiction.de\/lfd\/teresa-casanueva-und-maria-otterbein\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/linesfiction.de\/lfd\/"},{"@type":"ListItem","position":2,"name":"Teresa Casanueva und Maria Otterbein"}]},{"@type":"WebSite","@id":"https:\/\/linesfiction.de\/lfd\/#website","url":"https:\/\/linesfiction.de\/lfd\/","name":"Lines Fiction - Zeichnung & Animation - Drawing & Animation","description":"","publisher":{"@id":"https:\/\/linesfiction.de\/lfd\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/linesfiction.de\/lfd\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/linesfiction.de\/lfd\/#organization","name":"Lines Fiction","url":"https:\/\/linesfiction.de\/lfd\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/linesfiction.de\/lfd\/#\/schema\/logo\/image\/","url":"https:\/\/linesfiction.de\/lfd\/wp-content\/uploads\/2022\/12\/linesfiction_logo_instagram.jpg","contentUrl":"https:\/\/linesfiction.de\/lfd\/wp-content\/uploads\/2022\/12\/linesfiction_logo_instagram.jpg","width":1080,"height":1077,"caption":"Lines Fiction"},"image":{"@id":"https:\/\/linesfiction.de\/lfd\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/linesfiction\/","https:\/\/x.com\/linesfiction","https:\/\/www.instagram.com\/linesfiction\/"]},{"@type":"Person","@id":"https:\/\/linesfiction.de\/lfd\/#\/schema\/person\/f8d3cb2f3f3d7c9d441be87acf0de8f4","name":"lines","url":"https:\/\/linesfiction.de\/lfd\/author\/linesfiktion\/"}]}},"_links":{"self":[{"href":"https:\/\/linesfiction.de\/lfd\/wp-json\/wp\/v2\/posts\/3981","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/linesfiction.de\/lfd\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/linesfiction.de\/lfd\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/linesfiction.de\/lfd\/wp-json\/wp\/v2\/users\/9"}],"replies":[{"embeddable":true,"href":"https:\/\/linesfiction.de\/lfd\/wp-json\/wp\/v2\/comments?post=3981"}],"version-history":[{"count":4,"href":"https:\/\/linesfiction.de\/lfd\/wp-json\/wp\/v2\/posts\/3981\/revisions"}],"predecessor-version":[{"id":3986,"href":"https:\/\/linesfiction.de\/lfd\/wp-json\/wp\/v2\/posts\/3981\/revisions\/3986"}],"wp:attachment":[{"href":"https:\/\/linesfiction.de\/lfd\/wp-json\/wp\/v2\/media?parent=3981"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/linesfiction.de\/lfd\/wp-json\/wp\/v2\/categories?post=3981"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/linesfiction.de\/lfd\/wp-json\/wp\/v2\/tags?post=3981"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}